﻿{"id":58880,"date":"2017-05-19T11:13:02","date_gmt":"2017-05-19T11:13:02","guid":{"rendered":"http:\/\/www.metrolisboa.pt\/?p=58880"},"modified":"2017-05-19T11:13:02","modified_gmt":"2017-05-19T11:13:02","slug":"incidente-passageiro-na-estacao-campos","status":"publish","type":"post","link":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/","title":{"rendered":"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos"},"content":{"rendered":"<p>O Metropolitano de Lisboa confirma a ocorr\u00eancia verificada com um passageiro, hoje cerca das 08h59, na esta\u00e7\u00e3o Entre Campos, que obrigou ao corte da circula\u00e7\u00e3o na linha Amarela por motivos alheios \u00e0 empresa.<\/p>\n<p>A circula\u00e7\u00e3o da linha Amarela esteve interrompida das 08:59 \u00e0s 10:25, altura em que foram repostas as condi\u00e7\u00f5es de seguran\u00e7a adequadas ao restabelecimento da mesma.<\/p>\n<p>O passageiro sinistrado foi assistido pelo INEM no local e transportado para o hospital Sta. Maria.<\/p>\n<p>O Metropolitano de Lisboa lamenta o sucedido tendo tomado de imediato as medidas necess\u00e1rias, em articula\u00e7\u00e3o com as entidades envolvidas, no sentido de proceder \u00e0 normal reposi\u00e7\u00e3o do seu servi\u00e7o de transporte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Metropolitano de Lisboa presta esclarecimento sobre o incidente com passageiro ocorrido na esta\u00e7\u00e3o Entre Campos<\/p>\n","protected":false},"author":1,"featured_media":58759,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[18],"class_list":["post-58880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria","tag-noticias-2017"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incidente com passageiro na esta\u00e7\u00e3o Entre Campos - Metropolitano de Lisboa, EPE - English<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos - Metropolitano de Lisboa, EPE - English\" \/>\n<meta property=\"og:description\" content=\"O Metropolitano de Lisboa presta esclarecimento sobre o incidente com passageiro ocorrido na esta\u00e7\u00e3o Entre Campos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/\" \/>\n<meta property=\"og:site_name\" content=\"Metropolitano de Lisboa, EPE - English\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-19T11:13:02+00:00\" \/>\n<meta name=\"author\" content=\"siteml_tl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"siteml_tl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/\"},\"author\":{\"name\":\"siteml_tl\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#\\\/schema\\\/person\\\/eacaceae3ccbf5f1201aa29493ad932f\"},\"headline\":\"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos\",\"datePublished\":\"2017-05-19T11:13:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/\"},\"wordCount\":120,\"image\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Not\u00edcias 2017\"],\"articleSection\":[\"Sem categoria\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/\",\"url\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/\",\"name\":\"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos - Metropolitano de Lisboa, EPE - English\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-05-19T11:13:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#\\\/schema\\\/person\\\/eacaceae3ccbf5f1201aa29493ad932f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/05\\\/19\\\/incidente-passageiro-na-estacao-campos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/\",\"name\":\"Metropolitano de Lisboa, EPE - English\",\"description\":\"Mais um site Sites de Metropolitano de Lisboa, E.P.E.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#\\\/schema\\\/person\\\/eacaceae3ccbf5f1201aa29493ad932f\",\"name\":\"siteml_tl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g\",\"caption\":\"siteml_tl\"},\"url\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/author\\\/siteml_tl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos - Metropolitano de Lisboa, EPE - English","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/","og_locale":"en_US","og_type":"article","og_title":"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos - Metropolitano de Lisboa, EPE - English","og_description":"O Metropolitano de Lisboa presta esclarecimento sobre o incidente com passageiro ocorrido na esta\u00e7\u00e3o Entre Campos","og_url":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/","og_site_name":"Metropolitano de Lisboa, EPE - English","article_published_time":"2017-05-19T11:13:02+00:00","author":"siteml_tl","twitter_card":"summary_large_image","twitter_misc":{"Written by":"siteml_tl","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#article","isPartOf":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/"},"author":{"name":"siteml_tl","@id":"https:\/\/www.metrolisboa.pt\/en\/#\/schema\/person\/eacaceae3ccbf5f1201aa29493ad932f"},"headline":"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos","datePublished":"2017-05-19T11:13:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/"},"wordCount":120,"image":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#primaryimage"},"thumbnailUrl":"","keywords":["Not\u00edcias 2017"],"articleSection":["Sem categoria"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/","url":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/","name":"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos - Metropolitano de Lisboa, EPE - English","isPartOf":{"@id":"https:\/\/www.metrolisboa.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#primaryimage"},"image":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-05-19T11:13:02+00:00","author":{"@id":"https:\/\/www.metrolisboa.pt\/en\/#\/schema\/person\/eacaceae3ccbf5f1201aa29493ad932f"},"breadcrumb":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/05\/19\/incidente-passageiro-na-estacao-campos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.metrolisboa.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Incidente com passageiro na esta\u00e7\u00e3o Entre Campos"}]},{"@type":"WebSite","@id":"https:\/\/www.metrolisboa.pt\/en\/#website","url":"https:\/\/www.metrolisboa.pt\/en\/","name":"Metropolitano de Lisboa, EPE - English","description":"Mais um site Sites de Metropolitano de Lisboa, E.P.E.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metrolisboa.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.metrolisboa.pt\/en\/#\/schema\/person\/eacaceae3ccbf5f1201aa29493ad932f","name":"siteml_tl","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g","caption":"siteml_tl"},"url":"https:\/\/www.metrolisboa.pt\/en\/author\/siteml_tl\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":false,"_links":{"self":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/posts\/58880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/comments?post=58880"}],"version-history":[{"count":0,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/posts\/58880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/media?parent=58880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/categories?post=58880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/tags?post=58880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}