﻿{"id":59629,"date":"2017-09-14T00:01:55","date_gmt":"2017-09-14T00:01:55","guid":{"rendered":"http:\/\/www.metrolisboa.pt\/?p=59629"},"modified":"2017-09-14T00:01:55","modified_gmt":"2017-09-14T00:01:55","slug":"frequencia-comboios-horario-inverno","status":"publish","type":"post","link":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/","title":{"rendered":"Frequ\u00eancia de comboios | Inverno 17\/18"},"content":{"rendered":"<p>Como habitual, o arranque do ano letivo marca a entrada do hor\u00e1rio de Inverno no Metropolitano de Lisboa, com uma oferta de comboios refor\u00e7ada e ajustada \u00e0 procura existente.<br \/>\nNo dia 18 de setembro entra em vigor o hor\u00e1rio de Inverno do Metro, prolongando-se at\u00e9 ao m\u00eas de junho de 2018. &nbsp;As principais frequ\u00eancias do hor\u00e1rio de Inverno aos dias \u00fateis, s\u00e3o as seguintes:<\/p>\n<p>[four_columns ]<a href=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-azul.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58671\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-azul.png\" alt=\"\" width=\"75\" height=\"45\"><\/a><\/p>\n<table class=\"easy-table-creator tablesorter\">\n<tbody>\n<tr>\n<td>07h30 \u2013 09h30<\/td>\n<td>04\u201955\u201d<\/td>\n<\/tr>\n<tr>\n<td>09h31 \u2013 10h00<\/td>\n<td>05\u201915\u201d<\/td>\n<\/tr>\n<tr>\n<td>16h30 \u2013 19h00<\/td>\n<td>05\u201915\u201d<\/td>\n<\/tr>\n<tr>\n<td>19h01 \u2013 20h00<\/td>\n<td>06\u201910\u201d<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/four_columns] [four_columns ]<a href=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-amarela.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58668\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-amarela.png\" alt=\"\" width=\"99\" height=\"45\"><\/a><\/p>\n<table class=\"easy-table-creator tablesorter\">\n<tbody>\n<tr>\n<td>07h15 \u2013 09h30<\/td>\n<td>04\u201920\u201d<\/td>\n<\/tr>\n<tr>\n<td>09h31 \u2013 10h00<\/td>\n<td>05\u201900\u201d<\/td>\n<\/tr>\n<tr>\n<td>16h40 \u2013 17h30<\/td>\n<td>04\u201940\u201d&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>17h31 \u2013 19h00<\/td>\n<td>04\u201945\u201d<\/td>\n<\/tr>\n<tr>\n<td>19h01 \u2013 19h30<\/td>\n<td>06\u201910\u201d<\/td>\n<\/tr>\n<tr>\n<td>19h31 \u2013 20h30<\/td>\n<td>06\u201950\u201d<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/four_columns] [four_columns ]<a href=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-verde.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58669\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-verde.png\" alt=\"\" width=\"85\" height=\"45\"><\/a><\/p>\n<table class=\"easy-table-creator tablesorter\">\n<tbody>\n<tr>\n<td>07h15 \u2013 10h00<\/td>\n<td>05\u201935\u201d<\/td>\n<\/tr>\n<tr>\n<td>16h15 \u2013 20h30<\/td>\n<td>05\u201935\u201d<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/four_columns] [four_columns_last ]<a href=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-vermelha.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-58670\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/simbolo-l-vermelha.png\" alt=\"\" width=\"106\" height=\"45\"><\/a><\/p>\n<table class=\"easy-table-creator tablesorter\">\n<tbody>\n<tr>\n<td>07h10 \u2013 09h45<\/td>\n<td>06\u201915\u201d<\/td>\n<\/tr>\n<tr>\n<td>16h30 \u2013 19h15<\/td>\n<td>06\u201915\u201d<\/td>\n<\/tr>\n<tr>\n<td>19h15 \u2013 20h30<\/td>\n<td>07\u201905\u201d<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/four_columns_last]<br \/>\nConsulte o hor\u00e1rio completo por linha nos separadores abaixo dispon\u00edveis.<\/p>\n<p>[accordion collapse=&#8221;yes&#8221;] [panel title=&#8221; Linha Azul &#8221; ] <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-58138 size-full\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/dle_site-azul.png\" alt=\"dle_site-azul\" width=\"625\" height=\"107\"><\/p>\n<p><strong>[two_columns ]Dias \u00fateis<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><b>Frequ\u00eancia<\/b><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 07h00<\/td>\n<td>07&#8217;30&#8221;<\/td>\n<\/tr>\n<tr>\n<td>07h01 &#8211; 07h30<\/td>\n<td>06&#8217;10&#8221;<\/td>\n<\/tr>\n<tr>\n<td>07h31 &#8211; 09h30<strong>&nbsp;<\/strong><\/td>\n<td>04&#8217;55&#8221;<\/td>\n<\/tr>\n<tr>\n<td>09h31 &#8211; 10h00<\/td>\n<td>05&#8217;15&#8221;<\/td>\n<\/tr>\n<tr>\n<td>10h01 &#8211; 16h30<\/td>\n<td>06&#8217;40&#8221;<\/td>\n<\/tr>\n<tr>\n<td>16h31 &#8211; 19h00<\/td>\n<td>05&#8217;15&#8221;<\/td>\n<\/tr>\n<tr>\n<td>19h01 &#8211; 20h00<\/td>\n<td>06&#8217;10&#8221;<\/td>\n<\/tr>\n<tr>\n<td>20h01 &#8211; 20h30<\/td>\n<td>06&#8217;40&#8221;<\/td>\n<\/tr>\n<tr>\n<td>20h31 &#8211; 21h00<\/td>\n<td>07&#8217;20&#8221;<\/td>\n<\/tr>\n<tr>\n<td>21h01 &#8211; 21h30<\/td>\n<td>08&#8217;15&#8221;<\/td>\n<\/tr>\n<tr>\n<td>21h31 &#8211; 22h30<\/td>\n<td>08&#8217;05&#8221;<\/td>\n<\/tr>\n<tr>\n<td>22h31 &#8211; 01h00<\/td>\n<td>10&#8217;45&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>[\/two_columns] [two_columns_last ]Fins de semana e feriados<br \/>\n<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><strong><b>Frequ\u00eancia<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 08h30<\/td>\n<td>08&#8217;00&#8221;<\/td>\n<\/tr>\n<tr>\n<td>08h31 &#8211; 09h30<\/td>\n<td>08&#8217;05&#8221;<\/td>\n<\/tr>\n<tr>\n<td>09h31 &#8211; 10h30<\/td>\n<td>08&#8217;00&#8221;<\/td>\n<\/tr>\n<tr>\n<td>10h31 &#8211; 11h30<\/td>\n<td>08&#8217;05&#8221;<\/td>\n<\/tr>\n<tr>\n<td>11h31 &#8211; 19h30<\/td>\n<td>08&#8217;10&#8221;<\/td>\n<\/tr>\n<tr>\n<td>19h31 &#8211; 22h30<\/td>\n<td>08&#8217;00&#8221;<\/td>\n<\/tr>\n<tr>\n<td>22h31 &#8211; 01h00<\/td>\n<td>10&#8217;40&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/two_columns_last] Circula\u00e7\u00e3o de comboios com 3 carruagens:<br \/>\n&#8211; Dias \u00fateis, a partir das 21h30<br \/>\n&#8211; Fins de semana e feriados durante todo o hor\u00e1rio de explora\u00e7\u00e3o &#8211; 06h30 &#8211; 1h.<\/p>\n<p><strong>As frequ\u00eancias indicadas s\u00e3o tempos m\u00e9dios aproximados, salvo perturba\u00e7\u00f5es<\/strong>.[\/panel] [panel title=&#8221; Linha Amarela &#8221; ]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-58139 size-full\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/dle_site-amarela.png\" alt=\"dle_site-amarela\" width=\"625\" height=\"107\"><\/p>\n<p><strong>[two_columns ]Dias \u00fateis<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><strong><b>Frequ\u00eancia<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 07h15<\/td>\n<td>07&#8217;50&#8221;<\/td>\n<\/tr>\n<tr>\n<td>07h16 &#8211; 09h30<\/td>\n<td>04&#8217;20&#8221;<\/td>\n<\/tr>\n<tr>\n<td>09h31 &#8211; 10h00<\/td>\n<td>05&#8217;00&#8221;<\/td>\n<\/tr>\n<tr>\n<td>10h01 &#8211; 16h40<\/td>\n<td>05&#8217;50&#8221;&nbsp;<span style=\"color: #0000ff\"><strong>\u00b9<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td>10h01 &#8211; 16h40<\/td>\n<td>11&#8217;40&#8221;&nbsp;<span style=\"color: #0000ff\"><strong>\u00b2<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td>16h41 &#8211; 17h30<\/td>\n<td>04&#8217;40&#8221;<\/td>\n<\/tr>\n<tr>\n<td>17h31 &#8211; 19h00<\/td>\n<td>04&#8217;45&#8221;<\/td>\n<\/tr>\n<tr>\n<td>19h01 &#8211; 19h30<\/td>\n<td>06&#8217;10&#8221;<\/td>\n<\/tr>\n<tr>\n<td>19h31 &#8211; 20h00<\/td>\n<td>06&#8217;50&#8221;<\/td>\n<\/tr>\n<tr>\n<td>20h01 &#8211; 21h00<\/td>\n<td>08&#8217;55&#8221;<\/td>\n<\/tr>\n<tr>\n<td>21h01 &#8211; 22h00<\/td>\n<td>08&#8217;45&#8221;<\/td>\n<\/tr>\n<tr>\n<td>22h01 &#8211; 01h00<\/td>\n<td>10&#8217;30&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"color: #0000ff\"><span style=\"color: #000000\">[styledbox type=&#8221;information&#8221; ]<\/span><\/span><strong><span style=\"color: #0000ff\">\u00b9<\/span><\/strong> Percurso Rato \u00ab&#8211;\u00bb Campo Grande<br \/>\n<span style=\"color: #0000ff\"><strong>\u00b2<\/strong><\/span> Percurso Campo Grande \u00ab&#8211;\u00bb Odivelas[\/styledbox]<\/p>\n<p>[\/two_columns] [two_columns_last ]Fins de semana e feriados<\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><strong><b>Frequ\u00eancia<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 07h30<\/td>\n<td>08&#8217;40&#8221;<\/td>\n<\/tr>\n<tr>\n<td>07h31 &#8211; 20h30<\/td>\n<td>08&#8217;45&#8221;<\/td>\n<\/tr>\n<tr>\n<td>20h31 &#8211; 01h00<\/td>\n<td>10&#8217;25&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/two_columns_last]<\/p>\n<p>Circula\u00e7\u00e3o de comboios com 3 carruagens:<br \/>\n&#8211; Dias \u00fateis, a partir das 20h30<br \/>\n&#8211; Fins de semana e feriados durante todo o hor\u00e1rio de explora\u00e7\u00e3o &#8211; 06h30 &#8211; 1h.<\/p>\n<p><strong>As frequ\u00eancias indicadas s\u00e3o tempos m\u00e9dios aproximados, salvo perturba\u00e7\u00f5es<\/strong>.[\/panel] [panel title=&#8221; Linha Verde &#8221; ]<a href=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/DLE_LinhaVerde_ArroiosEncerrado.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-59268\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/DLE_LinhaVerde_ArroiosEncerrado.png\" alt=\"\" width=\"625\" height=\"107\"><\/a><\/p>\n<p><strong>[two_columns ]Dias \u00fateis<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><strong><b>Frequ\u00eancia<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 07h15<\/td>\n<td>06&#8217;50&#8221;<\/td>\n<\/tr>\n<tr>\n<td>07h16 &#8211; 10h00<\/td>\n<td>05&#8217;35&#8221;<\/td>\n<\/tr>\n<tr>\n<td>10h01 &#8211; 16h15<\/td>\n<td>06&#8217;05&#8221;<\/td>\n<\/tr>\n<tr>\n<td>16h16 &#8211; 20h30<\/td>\n<td>05&#8217;35&#8221;<\/td>\n<\/tr>\n<tr>\n<td>20h31 &#8211; 21h00<\/td>\n<td>06&#8217;00&#8221;<\/td>\n<\/tr>\n<tr>\n<td>21h01 &#8211; 22h15<\/td>\n<td>07&#8217;55&#8221;<\/td>\n<\/tr>\n<tr>\n<td>22h16 &#8211; 01h00<\/td>\n<td>11&#8217;50&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>[\/two_columns] [two_columns_last ]Fins de semana e feriados<br \/>\n<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><strong><b>Frequ\u00eancia<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 21h30<\/td>\n<td>08&#8217;05&#8221;<\/td>\n<\/tr>\n<tr>\n<td>21h31 &#8211; 22h30<\/td>\n<td>09&#8217;30&#8221;<\/td>\n<\/tr>\n<tr>\n<td>22h31 &#8211; 01h00<\/td>\n<td>11&#8217;50&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/two_columns_last][styledbox type=&#8221;information&#8221; ]Circula\u00e7\u00e3o de comboios com 3 carruagens:<br \/>\n\u2013 Dias \u00fateis, a partir das 20h30<br \/>\n\u2013 Fins de semana e feriados durante todo o hor\u00e1rio de explora\u00e7\u00e3o \u2013 06h30 \u2013 1h.[\/styledbox]<\/p>\n<p><strong>As frequ\u00eancias indicadas s\u00e3o tempos m\u00e9dios aproximados, salvo perturba\u00e7\u00f5es<\/strong>.[\/panel][panel title=&#8221; Linha Vermelha &#8221; ]<img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-58141 size-full\" src=\"https:\/\/www.metrolisboa.pt\/wp-content\/uploads\/dle_site-vermelha.png\" alt=\"dle_site-vermelha\" width=\"625\" height=\"107\"><\/p>\n<p><strong>[two_columns ]Dias \u00fateis<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><strong><b>Frequ\u00eancia<\/b><\/strong><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 07h10<\/td>\n<td>09&#8217;45&#8221;<\/td>\n<\/tr>\n<tr>\n<td>07h11 &#8211; 09h45<\/td>\n<td>06&#8217;15&#8221;<\/td>\n<\/tr>\n<tr>\n<td>09h46 &#8211; 16h30<\/td>\n<td>07&#8217;00&#8221;<\/td>\n<\/tr>\n<tr>\n<td>16h31 &#8211; 19h15<\/td>\n<td>06&#8217;15&#8221;<\/td>\n<\/tr>\n<tr>\n<td>19h16 &#8211; 20h30<\/td>\n<td>07&#8217;05&#8221;&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>20h31 &#8211; 22h30<\/td>\n<td>07&#8217;55&#8221;<\/td>\n<\/tr>\n<tr>\n<td>22h31 &#8211; 01h00<\/td>\n<td>09&#8217;25&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>[\/two_columns] [two_columns_last ]Fins de semana e feriados<br \/>\n<\/strong><\/p>\n<table class=\"easy-table-creator tablesorter\" style=\"width: 100%\">\n<tbody>\n<tr>\n<td><strong>Periodo hor\u00e1rio<\/strong><\/td>\n<td><b>Frequ\u00eancia<\/b><\/td>\n<\/tr>\n<tr>\n<td>06h30 &#8211; 22h15<\/td>\n<td>08&#8217;00&#8221;&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>22h16 &#8211; 00h00<\/td>\n<td>09&#8217;35&#8221;&nbsp;<\/td>\n<\/tr>\n<tr>\n<td>00h01 &#8211; 01h00<\/td>\n<td>09&#8217;25&#8221;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/two_columns_last]Circula\u00e7\u00e3o de comboios com 3 carruagens:<br \/>\n&#8211; Dias \u00fateis, a partir das 20h30<br \/>\n&#8211; Fins de semana e feriados durante todo o hor\u00e1rio de explora\u00e7\u00e3o &#8211; 06h30 &#8211; 1h.<\/p>\n<p><strong>As frequ\u00eancias indicadas s\u00e3o tempos m\u00e9dios aproximados, salvo perturba\u00e7\u00f5es<\/strong>.[\/panel] [\/accordion]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como habitual, o arranque do ano letivo marca a entrada do hor\u00e1rio de Inverno no Metropolitano de Lisboa, com uma oferta de comboios refor\u00e7ada e ajustada \u00e0 procura existente. No dia 18 de setembro entra em vigor o hor\u00e1rio de Inverno do Metro, prolongando-se at\u00e9 ao m\u00eas de junho de 2018. &nbsp;As principais frequ\u00eancias do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":59627,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[2,9],"tags":[],"class_list":["post-59629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquivo-de-noticias","category-noticias-2017"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frequ\u00eancia de comboios | Inverno 17\/18 - Metropolitano de Lisboa, EPE - English<\/title>\n<meta name=\"description\" content=\"Hor\u00e1rio de Inverno entra em vigor a partir do dia 18 de setembro. Consulte as novas frequ\u00eancia de comboios do Metro nesta p\u00e1gina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frequ\u00eancia de comboios | Inverno 17\/18 - Metropolitano de Lisboa, EPE - English\" \/>\n<meta property=\"og:description\" content=\"Hor\u00e1rio de Inverno entra em vigor a partir do dia 18 de setembro. Consulte as novas frequ\u00eancia de comboios do Metro nesta p\u00e1gina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/\" \/>\n<meta property=\"og:site_name\" content=\"Metropolitano de Lisboa, EPE - English\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-14T00:01:55+00:00\" \/>\n<meta name=\"author\" content=\"siteml_tl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"siteml_tl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/\"},\"author\":{\"name\":\"siteml_tl\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#\\\/schema\\\/person\\\/eacaceae3ccbf5f1201aa29493ad932f\"},\"headline\":\"Frequ\u00eancia de comboios | Inverno 17\\\/18\",\"datePublished\":\"2017-09-14T00:01:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/\"},\"wordCount\":733,\"image\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Arquivo de Not\u00edcias\",\"Not\u00edcias 2017\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/\",\"url\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/\",\"name\":\"Frequ\u00eancia de comboios | Inverno 17\\\/18 - Metropolitano de Lisboa, EPE - English\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2017-09-14T00:01:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#\\\/schema\\\/person\\\/eacaceae3ccbf5f1201aa29493ad932f\"},\"description\":\"Hor\u00e1rio de Inverno entra em vigor a partir do dia 18 de setembro. Consulte as novas frequ\u00eancia de comboios do Metro nesta p\u00e1gina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/2017\\\/09\\\/14\\\/frequencia-comboios-horario-inverno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frequ\u00eancia de comboios | Inverno 17\\\/18\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/\",\"name\":\"Metropolitano de Lisboa, EPE - English\",\"description\":\"Mais um site Sites de Metropolitano de Lisboa, E.P.E.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/#\\\/schema\\\/person\\\/eacaceae3ccbf5f1201aa29493ad932f\",\"name\":\"siteml_tl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g\",\"caption\":\"siteml_tl\"},\"url\":\"https:\\\/\\\/www.metrolisboa.pt\\\/en\\\/author\\\/siteml_tl\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frequ\u00eancia de comboios | Inverno 17\/18 - Metropolitano de Lisboa, EPE - English","description":"Hor\u00e1rio de Inverno entra em vigor a partir do dia 18 de setembro. Consulte as novas frequ\u00eancia de comboios do Metro nesta p\u00e1gina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/","og_locale":"en_US","og_type":"article","og_title":"Frequ\u00eancia de comboios | Inverno 17\/18 - Metropolitano de Lisboa, EPE - English","og_description":"Hor\u00e1rio de Inverno entra em vigor a partir do dia 18 de setembro. Consulte as novas frequ\u00eancia de comboios do Metro nesta p\u00e1gina.","og_url":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/","og_site_name":"Metropolitano de Lisboa, EPE - English","article_published_time":"2017-09-14T00:01:55+00:00","author":"siteml_tl","twitter_card":"summary_large_image","twitter_misc":{"Written by":"siteml_tl","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#article","isPartOf":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/"},"author":{"name":"siteml_tl","@id":"https:\/\/www.metrolisboa.pt\/en\/#\/schema\/person\/eacaceae3ccbf5f1201aa29493ad932f"},"headline":"Frequ\u00eancia de comboios | Inverno 17\/18","datePublished":"2017-09-14T00:01:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/"},"wordCount":733,"image":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#primaryimage"},"thumbnailUrl":"","articleSection":["Arquivo de Not\u00edcias","Not\u00edcias 2017"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/","url":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/","name":"Frequ\u00eancia de comboios | Inverno 17\/18 - Metropolitano de Lisboa, EPE - English","isPartOf":{"@id":"https:\/\/www.metrolisboa.pt\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#primaryimage"},"image":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#primaryimage"},"thumbnailUrl":"","datePublished":"2017-09-14T00:01:55+00:00","author":{"@id":"https:\/\/www.metrolisboa.pt\/en\/#\/schema\/person\/eacaceae3ccbf5f1201aa29493ad932f"},"description":"Hor\u00e1rio de Inverno entra em vigor a partir do dia 18 de setembro. Consulte as novas frequ\u00eancia de comboios do Metro nesta p\u00e1gina.","breadcrumb":{"@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.metrolisboa.pt\/en\/2017\/09\/14\/frequencia-comboios-horario-inverno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.metrolisboa.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Frequ\u00eancia de comboios | Inverno 17\/18"}]},{"@type":"WebSite","@id":"https:\/\/www.metrolisboa.pt\/en\/#website","url":"https:\/\/www.metrolisboa.pt\/en\/","name":"Metropolitano de Lisboa, EPE - English","description":"Mais um site Sites de Metropolitano de Lisboa, E.P.E.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metrolisboa.pt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.metrolisboa.pt\/en\/#\/schema\/person\/eacaceae3ccbf5f1201aa29493ad932f","name":"siteml_tl","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/280858a48f87f67c0054988ce334c914ea4366a35a1a3093f9230ea63e10bd0e?s=96&d=mm&r=g","caption":"siteml_tl"},"url":"https:\/\/www.metrolisboa.pt\/en\/author\/siteml_tl\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/posts\/59629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/comments?post=59629"}],"version-history":[{"count":0,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/posts\/59629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/media?parent=59629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/categories?post=59629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.metrolisboa.pt\/en\/wp-json\/wp\/v2\/tags?post=59629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}